{"id":9562,"date":"2023-07-20T18:09:34","date_gmt":"2023-07-20T18:09:34","guid":{"rendered":"https:\/\/versahinternational.com\/versah-international\/"},"modified":"2026-06-30T20:12:54","modified_gmt":"2026-06-30T20:12:54","slug":"versah-international","status":"publish","type":"page","link":"https:\/\/versahinternational.com\/pl\/versah-international\/","title":{"rendered":"Mi\u0119dzynarodowi Dystrybutorzy"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_custom_heading text=&#8221;VERSAH INTERNATIONAL&#8221; font_container=&#8221;tag:p|font_size:35|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;distributor-heading&#8221;][vc_tta_tabs title_tag=&#8221;h1&#8243; section_title_tag=&#8221;h1&#8243; style=&#8221;modern&#8221; spacing=&#8221;3&#8243; gap=&#8221;2&#8243; alignment=&#8221;center&#8221; active_section=&#8221;1&#8243; no_fill_content_area=&#8221;true&#8221; css=&#8221;.vc_custom_1774614558013{background-position: 0 0 !important;background-repeat: no-repeat !important;}&#8221;][vc_tta_section title=&#8221;North America &amp; South America&#8221; tab_id=&#8221;1689877850082-96ce6db3-b508&#8243;][vc_row_inner css=&#8221;.vc_custom_1702323788148{background-color: #222222 !important;}&#8221;][vc_column_inner][vc_single_image image=&#8221;6658&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/versah.com&#8221;][vc_btn title=&#8221;Shop Versah-North America&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fversah.com%2Fshop-versah%2F-1%2F&#8221;][vc_empty_space height=&#8221;50px&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1702326868842{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Argentina&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;25953&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/versahinternational.com\/pt-pt\/&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #999999;\">Alejandro Laciar Srl, Junin 969 7moA, Argentina<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #999999;\"><span class=\"s1\"><b><i><br \/>\nt:<\/i><\/b><\/span> +54-9-11-5053-7605<\/span><br \/>\n<span style=\"color: #999999;\"><span class=\"s1\"><b><i>e:<\/i><\/b><\/span> fal@alejandrolaciar.com \/ info@alejandrolaciar.com<\/span><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@alejandrolaciar.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Brazil&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;17871&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/versahinternational.com\/pt-pt\/&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #999999;\">Welfare Importa\u00e7\u00e3o Ltda. Rua Presidente Campos Sales Gloria, Joinville &#8211; SC,\u00a0Brazil<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #999999;\"><span class=\"s1\"><b><i><br \/>\nt:<\/i><\/b><\/span> +55 047 3433-6572<\/span><br \/>\n<span style=\"color: #999999;\"><span class=\"s1\"><b><i>e:<\/i><\/b><\/span> henrique@welfare.com.br<\/span><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;henrique@welfare.com.br&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Chile&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;17943&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/versahinternational.com\/es\/&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Via Ossea Chile, Luis Thayer Ojeda 0130 of 902, Providencia, Santiago<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +56 9 82194272<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> viaosseachile@gmail.com<br \/>\n<span class=\"s1\"><b><i>w: <\/i><\/b><a href=\"http:\/\/www.viaossea.cl\"><span style=\"color: #c4d600;\">Versah-Chile.com<\/span><\/a><\/span><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;viaosseachile@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1702326868842{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Colombia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;25880&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Carrera 43 A $ 27 A Sur &#8211; 86 Envigago, Antioquia, Colombia<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +57 604 444 7271<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> fernan.lopez@implatec.com<br \/>\n<span class=\"s1\"><b><i>w: <\/i><\/b><a href=\"http:\/\/www.implatec.com\"><span style=\"color: #c4d600;\">Versah-Colombia.com<\/span><\/a><\/span><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;fernan.lopez@implatec.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Mexico&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;17999&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Ometusco 37, Mexico City, Mexico, 06140<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +52 56 1036 0596<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> contacto@abdental.com.mx<span class=\"Apple-converted-space\"><br \/>\n<\/span><span class=\"s1\" style=\"font-size: 1.125rem;\"><b><i>w:<\/i><\/b><\/span><a href=\"https:\/\/www.abdental.com.mx\/?fbclid=IwY2xjawQqHN1leHRuA2FlbQIxMABicmlkETFlUjJGNHQwZ1ZKMTFJaVJqc3J0YwZhcHBfaWQQMjIyMDM5MTc4ODIwMDg5MgABHtG_zgK-_HHHaDE34T_Itc7m2L7DhNDnPinYiFwxEG-9cLebbrjcaz51B4RR_aem_-teEiYl9Imjxsd1z5TwUSQ\"><span style=\"font-size: 1.125rem; color: #c4d600;\"> Versah-Mexico.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;contacto@abdental.com.mx&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1721819238339{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Chile&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Galvarino Gallardo<br \/>\n1604 Providencia,<br \/>\nSantiago, Chile<\/p>\n<p style=\"text-align: center;\">t: +56 2 2242 8465\/+56 2 3251 8820<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> luis.chen@neobiotech.cl<br \/>\n<span class=\"s1\" style=\"font-size: 1.125rem;\"><b><i>w:<\/i><\/b><\/span><span class=\"Apple-converted-space\" style=\"font-size: 1.125rem;\">\u00a0 <\/span><a href=\"https:\/\/versahinternational.com\/es\/\"><span style=\"font-size: 1.125rem; color: #c4d600;\">Versah-Chile.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;luis.chen@neobiotech.cl&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Venezuela&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;17971&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Ave Venezuela<span class=\"Apple-converted-space\"> \u00a0<\/span>Edf Torre America Piso 10, Ofc 1008 Bello Monte Caracas, Venezuela<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +58(212)761-6237<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@prfgroupcorp.com<span class=\"Apple-converted-space\"><br \/>\n<\/span><span class=\"s1\"><b><i>w:<\/i><\/b><\/span> <a href=\"https:\/\/versahinternational.com\/es\/\"><span style=\"color: #c4d600;\">Versah-Venezuela.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@prfgroupcorp.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Costa Rica&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;17928&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/versahinternational.com\/pt-pt\/&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Odontoweb Professional S.A. Barrio Dent, San Pedro. De Taco Bell<span class=\"Apple-converted-space\"> \u00a0<\/span>100 oeste y 25 norte,<span class=\"Apple-converted-space\"> \u00a0<\/span>segunda casaala izquierda San Jose Costa Rica<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +506 22343133<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@odontowebcr.com<br \/>\n<span class=\"s1\" style=\"font-size: 1.125rem;\"><b><i>w:<\/i><\/b><\/span><a href=\"https:\/\/versahinternational.com\/es\/\"><span style=\"font-size: 1.125rem; color: #c4d600;\"> Versah-CostaRica.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@odontowebcr.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1721819238339{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Dominican Republic&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;17985&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">c\/ zing. Juan Paradas Bonilla No.3 Apt 3C, Santo Domingo, Dominican Republic<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +809-732-6390<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@roamalabs.com.do<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@roamalabs.com.do&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Puerto Rico&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;17957&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">JZ DENTAL EQUIPMENT AVE. CAMPO RICO, LOCAL GK36,<span class=\"Apple-converted-space\"> \u00a0<\/span>CAROLINA PR<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 787 249 6109<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> jzdentalequipment@gmail.com<br \/>\n<em><strong>w:<\/strong> <\/em><a href=\"https:\/\/versahinternational.com\/es\/\"><span style=\"color: #c4d600;\">Versah-PuertoRico.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;jzdentalequipment@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Europe&#8221; tab_id=&#8221;1689877880373-e356305b-629c&#8221;][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Austria&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18358&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Johann-Sebastian Bach Str. 42 85591 Vaterstetten Germany<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +49 (0) 8106 300-300<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> versah@adsystems.de<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;versah@adsystems.de&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Belgium&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18372&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Eikenenweg 71, 3520 Zonhoven<span class=\"Apple-converted-space\"><br \/>\n<\/span>Belgium<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +32 (0)11 822 650<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@proscan.be<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@proscan.be&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Bulgaria&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18386&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">12 Stoyan Zaimov str.<br \/>\nBulgaria, Sofia 1421<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> + 359 (2) 865 70 31 <span class=\"Apple-converted-space\"><br \/>\n<\/span><span class=\"s1\"><b><i>e:<\/i><\/b><\/span> office@vilem-bg.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;office@vilem-bg.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Croatia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18401&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\">MegaGen Dental d.o.o.,<br \/>\nDragutina Tadijanovica 3, 51000 Rijeka, Croatia<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +385 99 484 3500<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> megagen.croatia@gmail.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;megagen.croatia@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Cyprus&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18415&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Suite B11, 2nd Floor, METAXA 33, GLYFADA<br \/>\nGreece<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 00971 56 496 5580<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> ahmed@southernimplants.net<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;eropandelia@southernimplants.gr&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Czech Republic&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18429&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Pod Bateriemi 90\/9, Praha 6, 16200<br \/>\nCzechia<br \/>\n<span class=\"s1\"><b><i><br \/>\nt:<\/i><\/b><\/span> +420 727 832900<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> justhova@justdent.cz<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;justhova@justdent.cz&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Denmark&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18445&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Roskildevej 22, 26220 Albertslund, Denmark<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 004570211626<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@unidentdanmark.dk<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@unidentdanmark.dk&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Finland&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18473&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Niittyl\u00e4npolku 16, 00620 Helsinki<br \/>\nFinland<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +358201772300<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@unident.fi<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@unident.fi&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-France&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18503&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">79 Avenue Aristide Briand, 94118 Arcueil Cedex, France<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 01 41 98 34 06<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@pred.fr<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@pred.fr&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner][vc_empty_space height=&#8221;100px&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Germany&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18489&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Johann-Sebastian Bach Str. 42, 85591 Vaterstetten Germany<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +49 (0) 8106 300-300<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> versah@adsystems.de<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-Germany&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.adsystems.de%2Fshop%2Fparodontologie-und-implantologie%2Fosseodensification%2F&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Greece&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18532&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Suite B11, 2nd Floor, METAXA 33, GLYFADA, Greece<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i><br \/>\nt:<\/i><\/b><\/span> 0030 210 8982881<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> eropandelia@southernimplants.gr<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-Greece&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fversah-greece.gr%2Fsite%2Fshop%2F&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Italy&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;20238&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Via Enrico Fermi n. 20 37135<br \/>\nItaly<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 0458238611<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@revello.net<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@revello.net&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Ireland&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;27581&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Colchis House, Brassey Road, Shrewsbury, Shropshire SY3 7FA, United Kingdom<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +44 33 03300 585 498<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@versah.co.uk<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-Ireland&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.versah.co.uk%2F&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Lithuania&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;23404&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">UAB MegaGen\u00a0Baltics, Park Town Business Center, Lvivo 101, Vilnius 08104, Lithuania<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +37 06 524 9729<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@megagenbaltics.lt<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@megagenbaltics.lt&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Luxembourg&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18546&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Eikenenweg 71, 3520 Zonhoven,<br \/>\nBelgium<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +32 (0)11 822 650<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@proscan.be<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@proscan.be&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Malta&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18560&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">42A Main Street, Balzan BZN 1259, Malta<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +356 21447340<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@bart.com.mt<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@bart.com.mt&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Moldova&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18617&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Chi\u0219in\u0103u, Republic of Moldova<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +373 61 109 298<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> megagen.moldova@gmail.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;megagen.moldova@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Netherlands&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18631&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Eikenenweg 71, 3520 Zonhoven<span class=\"Apple-converted-space\"><br \/>\n<\/span>Belgium<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +32 (0)11 822 650<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@proscan.be<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@proscan.be&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner][vc_empty_space height=&#8221;100px&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Norway&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18645&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Gammelveien 36, 3189 Horten<br \/>\nNorway<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 004733035770<span class=\"Apple-converted-space\"><br \/>\n<\/span><span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@unident.no<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@unident.no&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Poland&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18660&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Global D Poland Sp.zo.o.Ul. Okolnik 11a\/69<br \/>\n00-368 Warszawa, Poland<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +48 22 258 80 80<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> zamowienia@globald.pl<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;zamowienia@globald.pl&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Portugal&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18674&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Rua De Laborim 68, 4430-128,<br \/>\nVila Nova da Gaia, Portugal<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +351 912 630 641<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> isalinacardoso@exaktus.pt<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;isalinacardoso@exaktus.pt&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Romania&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18688&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Brasov \u2013 500332, Traian 109, Street<br \/>\nRomania<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +40 268 315544<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> ian@medidentexim.ro<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-Romania&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fmedidentexim.ro%2Fversah_2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;18717&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_custom_heading text=&#8221;Versah-Slovakia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Pod Bateriemi 90\/9, Praha 6, 16200, Czechia<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +420 727 832900<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> justhova@justdent.cz<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;justhova@justdent.cz&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Sweden&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18760&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">V\u00e4sterhavsv\u00e4gen 2, 31177 Falkenberg<br \/>\nSweden<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 0046346732400<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@unident.se<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@unident.se&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Spain&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18746&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">C\/ de Balmes, 190, 4\u00ba<br \/>\nDistrito de Sarri\u00e0-Sant Gervasi<br \/>\n08006 Barcelona, Spain<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +34 671300783<span class=\"Apple-converted-space\"><br \/>\n<\/span><span class=\"s1\"><b><i>e:<\/i><\/b><\/span> versah@salugraftdental.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;versah@salugraftdental.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Ukraine&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18803&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Dentline company LCC, Nizhnuy Val 15, office 601, Kiev 01001, Ukraine<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +38050977953 &#8211; Gusiev Volodymyr<span class=\"Apple-converted-space\"><br \/>\n<\/span><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;+38050977953&#8243; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;fas fa-phone-volume&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-UK&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18817&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Colchis House, Brassey Road, Shrewsbury, Shropshire SY3 7FA, United Kingdom<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 03300 585 498<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@versah.co.uk<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-UK&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.versah.co.uk%2F&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1717673326397{background-color: #222222 !important;}&#8221;][vc_column_inner][vc_custom_heading text=&#8221;Partners Coming Soon&#8230;&#8221; font_container=&#8221;tag:p|font_size:25|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1690208948610{background-color: #333333 !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1737401844231{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Serbia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18703&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Stojana Stoleta<span class=\"Apple-converted-space\"> , <\/span>Arandjelovica 8, Serbia<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +38162339431<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> marijana@mastermaker.rs<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;marijana@mastermaker.rs&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Georgia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18517&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Dentalmarket LTD, D. Agmashenebeli 124, 0102 Tbilisi, Georgia<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +995 5992 023 93<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> richgroupgeorgia@yahoo.com<br \/>\n<span class=\"s1\"><b><i>w:<\/i><\/b><\/span> <a href=\"https:\/\/versahinternational.com\/\"><span style=\"color: #c4d600;\">Versah-Georgia.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;richgroupgeogria@yahoo.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Hungary&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;25030&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">500332, Traian 109, Street, Romania<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +40 268 315544<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> ian@medidentexim.ro<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-Hungary&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fmedidentexim.ro%2Fversah_2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1737401844231{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Bosnia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18832&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Stojana Stoleta<span class=\"Apple-converted-space\"> , <\/span>Arandjelovica 8,<br \/>\nSerbia<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +38162339431<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> marijana@mastermaker.rs<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;marijana@mastermaker.rs&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Slovenia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18731&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Stojana Stoleta, Arandjelovica 8,<br \/>\nSerbia<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +38162339431 <span class=\"Apple-converted-space\"><br \/>\n<\/span><span class=\"s1\"><b><i>e:<\/i><\/b><\/span> marijana@mastermakers.rs<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;marijana@mastermaker.rs&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Switzerland&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18788&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Johann-Sebastian Bach Str. 42, 85591 Vaterstetten, Germany<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +49 (0) 8106 300-300<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> versah@adsystems.de<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;versah@adsystems.de&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Asia&#8221; tab_id=&#8221;1689877147893-c7bb9039-e8d9&#8243;][vc_row_inner css=&#8221;.vc_custom_1715606027064{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Armenia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18050&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">37 Halabyan St. Yerevan 0038, Armenia<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +37477413336<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> g.nazloyan@gmail.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;g.nazloyan@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Hong Kong&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18065&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">5F-2, No. 102, ZhongPing Rd. Taoyuan Dist. Taoyuan City Taiwan 330<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +886 3 220 9722<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> amyyang@threea3a.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;amyyang@threea3a.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-India&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18079&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Apurva Complex, 56 Ganeshkind Road Aundh, Pune-411 007 India<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +91 70660 66215<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> amit@kataradental.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;amit@kataradental.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Japan&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;20289&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">MegaGen Japan,<br \/>\nSenba Midcube 4F,<span class=\"Apple-converted-space\"><br \/>\n<\/span>3-1-6 Kitakyuhojimachi, Chuo-ku,<span class=\"Apple-converted-space\"><br \/>\n<\/span>Osaka, Japan 541-0057<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 81-6281-3535<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@megagen.jp<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@megagen.jp&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Kazakhstan&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;27596&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Kazakhstan, Almaty,<br \/>\nUdarnaya 23\/1<span class=\"Apple-converted-space\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +7 707 881 881 8<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@idl-implants.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@idl-implants.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Malaysia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18094&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">TRIPLE A (M) SDN BHD<span class=\"Apple-converted-space\"> \u00a0<\/span>61A,<br \/>\nJalan Lazat Satu,<span class=\"Apple-converted-space\"><br \/>\n<\/span>Happy Garden,<span class=\"Apple-converted-space\"><br \/>\n<\/span>58200 Kuala Lumpur<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +60169716935<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> team@triplea3a.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;team@triplea3a.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Myanmar&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;25842&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">No. 118, 23rd Street,<br \/>\nLatha Tsp,<span class=\"Apple-converted-space\"><br \/>\n<\/span>Yangon, Myanmar<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +95-95408243, +95-973901055<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@oralcareproduct.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@oralcareproduct.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Nepal&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;25629&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Sky Med Pvt. Ltd.,<span class=\"Apple-converted-space\"><br \/>\n<\/span>1425\/29, Ring Road (North), Dhobighat-4,<br \/>\nLalitpur, Bagmati, 44700<span class=\"Apple-converted-space\"><br \/>\n<\/span>NEPAL<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +977 9851008409<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@skymed.com.np<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-Nepal&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:http%3A%2F%2Fwww.skymed.com.np&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Sri Lanka&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18180&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">George Steuart Health Ltd 7E Postmasters Place Off Templers Rd. Mount Lavinia Sri Lanka<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +94 11 4202800<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> sanjiva@gshealth.lk<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;sanjiva@gshealth.lk&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Taiwan&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18137&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">5F-2, No. 102, ZhongPing Rd.<br \/>\nTaoyuan Dist.<br \/>\nTaoyuan City<br \/>\nTaiwan 330<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +886 3 220 9722<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> amyyang@threea3a.com<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-Taiwan&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fdental3a.com%2Fproduct-tag%2Fversah%2F&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1717673289048{background-color: #222222 !important;}&#8221;][vc_column_inner][vc_custom_heading text=&#8221;Partners Coming Soon&#8230;&#8221; font_container=&#8221;tag:p|font_size:25|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1690207238152{background-color: #333333 !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1737040047515{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Singapore&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18108&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">TRIPLE A (M) SDN BHD 61A,<br \/>\nJalan Lazat Satu,<span class=\"Apple-converted-space\"><br \/>\n<\/span>Happy Garden,<span class=\"Apple-converted-space\"><br \/>\n<\/span>58200 Kuala Lumpur<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +60169716935<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> team@triplea3a.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;team@triplea3a.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Philippines&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;20215&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Unit 1816 &amp; 1817, 18th Flr,<br \/>\nHigh Street South Corporate Plaza, Tower1,<br \/>\n26th st., cor. 9th ave.,<br \/>\nBGC, Taguig city, Philippines 1630<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +63-270044977<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> megagen.implant.ph@gmail.com<br \/>\n<span class=\"s1\"><b><i>w:<\/i><\/b><\/span> <a href=\"https:\/\/versahinternational.com\/\"><span style=\"color: #c4d600;\">Versah-Philippines.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;megagen.implant.ph@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-South Korea&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18122&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">45, Secheon-ro 7-gil,<br \/>\nDalseong-gun,<span class=\"Apple-converted-space\"><br \/>\n<\/span>Daegu, Korea (42921)<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 82-53-222-3246<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> item.design@imegagen.com<br \/>\n<span class=\"s1\"><b><i>w:<\/i><\/b><\/span> <a href=\"https:\/\/versahinternational.com\/\"><span style=\"color: #c4d600;\">Versah-SouthKorea.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;item.design@imegagen.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1737040047515{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Thailand&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18151&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">MegaGen Implant (Thailand) Co., Ltd. (Head office), 13 Soi Bangna- Trad 25, Bangna Nuea Subdistrict, Bang na District Bangkok, 10260<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +66 21365244<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> sunhee.b@megagen.co.th<br \/>\n<span class=\"s1\"><b><i>w:<\/i><\/b><\/span> <a href=\"https:\/\/versahinternational.com\/\"><span style=\"color: #c4d600;\">Versah-Thailand.com<\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;sunhee.b@megagen.co.th&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Oceania&#8221; tab_id=&#8221;1689877864762-935a836b-515f&#8221;][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Australia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18020&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Unit 1\/53 Winton Road, Joondalup WA 6027<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +61 (0) 8 9466 2627<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> orders@versahaustralia.com.au<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-Australia&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fversahaustralia.com.au%2Fshop-densah-burs%2F&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-New Zealand&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18034&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Unit 1\/53 Winton Road, Joondalup WA 6027<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +61 (0) 8 9466 2627<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> orders@versahaustralia.com.au<\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Shop Versah-New Zealand&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#777777&#8243; custom_text=&#8221;#c4d600&#8243; size=&#8221;lg&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-shopping-cart&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fversahaustralia.com.au%2Fshop-densah-burs%2F&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Middle East &amp; Africa&#8221; tab_id=&#8221;1689877903399-7318599a-3a12&#8243;][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Algeria&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;21226&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">A\u00efn Allah Lot N\u00b002 Coop\u00e9rative El Bouroudj, D\u00e9ly Ibrahim 16047<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +213\u00a0561\u00a0675\u00a0748 \/ +213\u00a0233\u00a0098 73\/\u00a0+213 555 572 415<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> commercial@dentina-dz.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;commercial@dentina-dz.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Bahrain&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18327&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Armin Bldg., Corner Al Imam Saud Bin Abdul Aziz Branch Road &amp; Al Shariqah Street, Al Mohammadiyah 12364, Riyadh KSA;<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +966 11 4551416\/+966 55 4664661\/+966 53 556 0676<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@melatdental.com\/henaro@melatdental.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@melatdental.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Egypt&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18196&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">10 Nozha St. Cairo<span class=\"Apple-converted-space\"><br \/>\n<\/span>Egypt<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 002-01061555591<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@dentalexpressgroup.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@dentalexpressgroup.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Israel&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18224&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">142 Ahuza Street<span class=\"Apple-converted-space\"> \u00a0<\/span>Ra\u2019amama 43300<span class=\"Apple-converted-space\"><br \/>\n<\/span>Israel<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 972-97400336<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> drmazor@gmail.com<span class=\"Apple-converted-space\"><br \/>\n<\/span><\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;drmazor@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Kuwait&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18254&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Opposite Laila Tower, ATC Tower Salem Al Mubarak Street, Salmiya, 32060 Kuwait<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span><span class=\"Apple-converted-space\">\u00a0 <\/span>00964-783 570 4271<br \/>\n<span class=\"s2\"><b><i>e:<\/i><\/b><\/span> aloaloa.sb2017@gmail.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;aloaloa.sb2017@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Qatar&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18268&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">First Floor: Office No. 12<span class=\"Apple-converted-space\"> \u00a0<\/span>Zone 71,<br \/>\nStreet 750<span class=\"Apple-converted-space\"> \u00a0<\/span>Building No. 125 Qatar<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 0974-50050048<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> alaa.blueskydent@gmail.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;alaa@blueskydent.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1689877454934{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Saudi Arabia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18283&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Armin Bldg., Corner Al Imam Saud Bin Abdul Aziz Branch Road &amp; Al Shariqah Street, Al Mohammadiyah 12364, Riyadh KSA;<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +966 11 4551416<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> Versahsa@melatdental.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;Versahsa@melatdental.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Tunisia&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18297&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">81 Av Mongi Slim IMM Hedoui,1er etage,<br \/>\n6000 Gabes, TUNISIE<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +216 70 038 581 +216 98 660 106<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> medical.world@yahoo.fr<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;medical.world@yahoo.fr&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-UAE&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18311&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">SIM Drug Stores C04 England Y16<br \/>\nInternational City<span class=\"Apple-converted-space\"><br \/>\n<\/span>Dubai, UAE<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i><br \/>\nt:<\/i><\/b><\/span> +971 4 565 5022\/+971 56 496 5580<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> info@southern implants.net<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;info@southernimplants.net&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1717673235235{background-color: #222222 !important;}&#8221;][vc_column_inner][vc_custom_heading text=&#8221;Partners Coming Soon&#8230;&#8221; font_container=&#8221;tag:p|font_size:25|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1690209546956{background-color: #333333 !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1773757517954{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Iran&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18873&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Suite 3, Building 12, 13th Alley, Mir Emad St. Tehran 1587745414 Iran<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span><span class=\"Apple-converted-space\">\u00a0 <\/span>+98 21 877 64<br \/>\n<span class=\"s2\"><b><i>e:<\/i><\/b><\/span> ettekal@ettekal.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;ettekal@ettekal.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Iraq&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18210&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Iraq-Baghdad-Al Mansour Al daowdi, Dist 611 St 82, H2-13, Iraq<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span><span class=\"Apple-converted-space\">\u00a0 <\/span>00964-783 570 4271<br \/>\n<span class=\"s2\"><b><i>e:<\/i><\/b><\/span> aloaloa.sb2017@gmail.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;aloaloa.sb2017@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Lebanon&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18240&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">Ra\u2019as Al Naba\u2019a &#8211; Abdul Moula Chaar Street &#8211;<br \/>\nBeirut, Lebanon<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> +961 1 653 374<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> 1powerdental@gmail.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;1powerdental@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1773757517954{background-color: #222222 !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;Versah-Morocco&#8221; font_container=&#8221;tag:p|font_size:30|text_align:center|color:%23c4d600&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;18341&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\">IDentex Secteur 21 bloc M N \u00b08 Rue Dadi,<br \/>\nLocal N \u00b02 RDC Hay Riad,<br \/>\nRabat, Morocco<\/p>\n<p style=\"text-align: center;\"><span class=\"s1\"><b><i>t:<\/i><\/b><\/span> 00212643842690<br \/>\n<span class=\"s1\"><b><i>e:<\/i><\/b><\/span> h.identex@gmail.com<\/p>\n<p>[\/vc_column_text][vc_cta h2=&#8221;h.identex@gmail.com&#8221; h2_font_container=&#8221;tag:h2|font_size:35|text_align:center|color:%23c4d600&#8243; h2_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; h4_font_container=&#8221;tag:h4|font_size:25|text_align:center|color:%23ffffff&#8221; h4_google_fonts=&#8221;font_family:Source%20Sans%20Pro%3A200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C900%2C900italic|font_style:400%20regular%3A400%3Anormal&#8221; txt_align=&#8221;center&#8221; style=&#8221;custom&#8221; add_icon=&#8221;left&#8221; i_icon_fontawesome=&#8221;far fa-envelope&#8221; i_color=&#8221;custom&#8221; use_custom_fonts_h2=&#8221;true&#8221; use_custom_fonts_h4=&#8221;true&#8221; i_custom_color=&#8221;#c4d600&#8243; custom_background=&#8221;#222222&#8243;][\/vc_cta][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner][vc_empty_space height=&#8221;100px&#8221;][vc_column_text]<\/p>\n<h6><span style=\"color: #808080;\"> 10883 REV22 last updated: 06\/2026<\/span><\/h6>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_custom_heading text=&#8221;VERSAH INTERNATIONAL&#8221; font_container=&#8221;tag:p|font_size:35|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;distributor-heading&#8221;][vc_tta_tabs title_tag=&#8221;h1&#8243; section_title_tag=&#8221;h1&#8243; style=&#8221;modern&#8221; spacing=&#8221;3&#8243; gap=&#8221;2&#8243; alignment=&#8221;center&#8221; active_section=&#8221;1&#8243; no_fill_content_area=&#8221;true&#8221; css=&#8221;.vc_custom_1774614558013{background-position: 0 0 !important;background-repeat: no-repeat !important;}&#8221;][vc_tta_section<\/p>\n<p><a href=\"https:\/\/versahinternational.com\/pl\/versah-international\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\">Mi\u0119dzynarodowi Dystrybutorzy<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9562","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/versahinternational.com\/pl\/wp-json\/wp\/v2\/pages\/9562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/versahinternational.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/versahinternational.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/versahinternational.com\/pl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/versahinternational.com\/pl\/wp-json\/wp\/v2\/comments?post=9562"}],"version-history":[{"count":66,"href":"https:\/\/versahinternational.com\/pl\/wp-json\/wp\/v2\/pages\/9562\/revisions"}],"predecessor-version":[{"id":28257,"href":"https:\/\/versahinternational.com\/pl\/wp-json\/wp\/v2\/pages\/9562\/revisions\/28257"}],"wp:attachment":[{"href":"https:\/\/versahinternational.com\/pl\/wp-json\/wp\/v2\/media?parent=9562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}